{"id":89,"date":"2023-04-07T13:52:46","date_gmt":"2023-04-07T13:52:46","guid":{"rendered":"https:\/\/partnerafrica-senegal.hosting9.tn-rechenzentrum1.de\/?page_id=89"},"modified":"2023-04-19T16:20:40","modified_gmt":"2023-04-19T16:20:40","slug":"downloads","status":"publish","type":"page","link":"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/","title":{"rendered":"Downloads"},"content":{"rendered":"\n<div class=\"wp-block-columns doc1_main is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns doc_main is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column c3 f1 section-inner k111 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">        <div class=\"main-content-container container gdlr-item-start-content\">\n            <div class=\"gdlr-item gdlr-main-content\">\n                <div class=\"downloads_list\"><\/div>\n        \t<\/div>\n    \t<\/div>\n\n    \n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1412,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-89","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Downloads - Partnerafrica Senegal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Downloads - Partnerafrica Senegal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/\" \/>\n<meta property=\"og:site_name\" content=\"Partnerafrica Senegal\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-19T16:20:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.partnerafrica-senegal.org\/wp-content\/uploads\/2023\/04\/Layer-310-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1696\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/\",\"url\":\"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/\",\"name\":\"Downloads - Partnerafrica Senegal\",\"isPartOf\":{\"@id\":\"https:\/\/www.partnerafrica-senegal.org\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.partnerafrica-senegal.org\/wp-content\/uploads\/2023\/04\/Layer-310-scaled.jpg\",\"datePublished\":\"2023-04-07T13:52:46+00:00\",\"dateModified\":\"2023-04-19T16:20:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/#primaryimage\",\"url\":\"https:\/\/www.partnerafrica-senegal.org\/wp-content\/uploads\/2023\/04\/Layer-310-scaled.jpg\",\"contentUrl\":\"https:\/\/www.partnerafrica-senegal.org\/wp-content\/uploads\/2023\/04\/Layer-310-scaled.jpg\",\"width\":2560,\"height\":1696},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.partnerafrica-senegal.org\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Downloads\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.partnerafrica-senegal.org\/en\/#website\",\"url\":\"https:\/\/www.partnerafrica-senegal.org\/en\/\",\"name\":\"Partnerafrica Senegal\",\"description\":\"German-Ethiopian Textile Business Partnership\",\"publisher\":{\"@id\":\"https:\/\/www.partnerafrica-senegal.org\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.partnerafrica-senegal.org\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.partnerafrica-senegal.org\/en\/#organization\",\"name\":\"Partnerafrica Senegal\",\"url\":\"https:\/\/www.partnerafrica-senegal.org\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.partnerafrica-senegal.org\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.partnerafrica-senegal.org\/wp-content\/uploads\/2023\/04\/logo-gesamtmashe-1.svg\",\"contentUrl\":\"https:\/\/www.partnerafrica-senegal.org\/wp-content\/uploads\/2023\/04\/logo-gesamtmashe-1.svg\",\"width\":150,\"height\":30,\"caption\":\"Partnerafrica Senegal\"},\"image\":{\"@id\":\"https:\/\/www.partnerafrica-senegal.org\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Downloads - Partnerafrica Senegal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/","og_locale":"en_US","og_type":"article","og_title":"Downloads - Partnerafrica Senegal","og_url":"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/","og_site_name":"Partnerafrica Senegal","article_modified_time":"2023-04-19T16:20:40+00:00","og_image":[{"width":2560,"height":1696,"url":"https:\/\/www.partnerafrica-senegal.org\/wp-content\/uploads\/2023\/04\/Layer-310-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/","url":"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/","name":"Downloads - Partnerafrica Senegal","isPartOf":{"@id":"https:\/\/www.partnerafrica-senegal.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/#primaryimage"},"image":{"@id":"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/#primaryimage"},"thumbnailUrl":"https:\/\/www.partnerafrica-senegal.org\/wp-content\/uploads\/2023\/04\/Layer-310-scaled.jpg","datePublished":"2023-04-07T13:52:46+00:00","dateModified":"2023-04-19T16:20:40+00:00","breadcrumb":{"@id":"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/#primaryimage","url":"https:\/\/www.partnerafrica-senegal.org\/wp-content\/uploads\/2023\/04\/Layer-310-scaled.jpg","contentUrl":"https:\/\/www.partnerafrica-senegal.org\/wp-content\/uploads\/2023\/04\/Layer-310-scaled.jpg","width":2560,"height":1696},{"@type":"BreadcrumbList","@id":"https:\/\/www.partnerafrica-senegal.org\/en\/downloads\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.partnerafrica-senegal.org\/en\/"},{"@type":"ListItem","position":2,"name":"Downloads"}]},{"@type":"WebSite","@id":"https:\/\/www.partnerafrica-senegal.org\/en\/#website","url":"https:\/\/www.partnerafrica-senegal.org\/en\/","name":"Partnerafrica Senegal","description":"German-Ethiopian Textile Business Partnership","publisher":{"@id":"https:\/\/www.partnerafrica-senegal.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.partnerafrica-senegal.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.partnerafrica-senegal.org\/en\/#organization","name":"Partnerafrica Senegal","url":"https:\/\/www.partnerafrica-senegal.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.partnerafrica-senegal.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.partnerafrica-senegal.org\/wp-content\/uploads\/2023\/04\/logo-gesamtmashe-1.svg","contentUrl":"https:\/\/www.partnerafrica-senegal.org\/wp-content\/uploads\/2023\/04\/logo-gesamtmashe-1.svg","width":150,"height":30,"caption":"Partnerafrica Senegal"},"image":{"@id":"https:\/\/www.partnerafrica-senegal.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.partnerafrica-senegal.org\/en\/wp-json\/wp\/v2\/pages\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.partnerafrica-senegal.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.partnerafrica-senegal.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.partnerafrica-senegal.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.partnerafrica-senegal.org\/en\/wp-json\/wp\/v2\/comments?post=89"}],"version-history":[{"count":9,"href":"https:\/\/www.partnerafrica-senegal.org\/en\/wp-json\/wp\/v2\/pages\/89\/revisions"}],"predecessor-version":[{"id":1747,"href":"https:\/\/www.partnerafrica-senegal.org\/en\/wp-json\/wp\/v2\/pages\/89\/revisions\/1747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.partnerafrica-senegal.org\/en\/wp-json\/wp\/v2\/media\/1412"}],"wp:attachment":[{"href":"https:\/\/www.partnerafrica-senegal.org\/en\/wp-json\/wp\/v2\/media?parent=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}